{"id":2430,"date":"2017-07-11T07:55:07","date_gmt":"2017-07-11T07:55:07","guid":{"rendered":"http:\/\/www.grupozaragoza.com\/energias-renovables\/om\/"},"modified":"2024-08-09T07:44:15","modified_gmt":"2024-08-09T06:44:15","slug":"om","status":"publish","type":"page","link":"https:\/\/www.grupozaragoza.com\/fr\/energie-renouvelable\/om\/","title":{"rendered":"O&#038;M"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb el_class=\u00a0\u00bbmod_block pt_40&Prime;][vc_column][vc_column_text]<span style=\"font-weight: 400;\"><strong>Le but de notre service de maintenance est de maintenir le fonctionnement des installations dans des conditions optimales 365 jours par an<\/strong>.\u00a0<\/span>Pour ce faire, nous surveillons la production quotidiennement, nous effectuons la maintenance pr\u00e9ventive, les r\u00e9parations et une surveillance \u00e9troite, prolongeant la dur\u00e9e de vie des \u00e9quipements, l&rsquo;am\u00e9lioration de la s\u00e9curit\u00e9 et de r\u00e9duire les co\u00fbts de r\u00e9paration.<\/p>\n<p>Ensuite nous d\u00e9taillons les activit\u00e9s de maintenance pr\u00e9ventive des syst\u00e8mes photovolta\u00efques. Ce ne sont que les activit\u00e9s explicatives et ne sont pas exhaustives, car elles d\u00e9pendent \u00e9troitement des caract\u00e9ristiques techniques des composants install\u00e9s :[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbyes\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb background_color=\u00a0\u00bb#f4f4f4&Prime; el_class=\u00a0\u00bbmod_block imgText-resp-bottom\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h3>CONTR\u00d4LE DE LA PRODUCTION<\/h3>\n<p>[\/vc_column_text][vc_separator type=\u00a0\u00bbsmall\u00a0\u00bb position=\u00a0\u00bbleft\u00a0\u00bb][vc_row_inner row_type=\u00a0\u00bbrow\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb css_animation=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbsectionTable oneThirdLayout\u00a0\u00bb][vc_column_inner el_class=\u00a0\u00bboneThird\u00a0\u00bb width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb3596&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb qode_css_animation=\u00a0\u00bbelement_from_left\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb2\/3&Prime;][vc_column_text]GRUPO ZARAGOZ\u00c1 poss\u00e8de un centre de surveillance \u00e0 distance dans ses bureaux \u00e0 Corato (Italie) et Valence, avec d\u2019\u00e9quipement informatique et du personnel d\u00e9di\u00e9 \u00e0 la lecture continue des donn\u00e9es transmises par les installations photovolta\u00efques 7 jours par semaine.<\/p>\n<p>Cette surveillance constante permet de d\u00e9tecter tout d\u00e9faut ou dysfonctionnement et d&rsquo;\u00e9valuer le type d&rsquo;intervention. Dans les cas d&rsquo;anomalies l\u00e9g\u00e8res proc\u00e9deront rapidement dans les interventions de maintenance pr\u00e9ventive, alors que dans le cas d\u2019anomalies plus importantes le client sera rapidement notifi\u00e9 au cas o\u00f9 il faudrait recourir \u00e0 une action corrective et il sera soutenu par la meilleure solution.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbyes\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb el_class=\u00a0\u00bbmod_block\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h3>NETTOYAGE ET CONTR\u00d4LE DES MODULES<\/h3>\n<p>[\/vc_column_text][vc_separator type=\u00a0\u00bbsmall\u00a0\u00bb position=\u00a0\u00bbleft\u00a0\u00bb][vc_row_inner row_type=\u00a0\u00bbrow\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb css_animation=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbimgText-top sectionTable oneThirdLayout\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text]Le nettoyage des modules est n\u00e9cessaire pour \u00e9viter un stockage prolong\u00e9 et permanent des objets et des d\u00e9p\u00f4ts de poussi\u00e8re sur la surface. Le nettoyage s&rsquo;effectuera avec un nettoyant \u00e0 haute pression en utilisant de l&rsquo;eau adoucie, en \u00e9vitant l&rsquo;utilisation de produits abrasifs.<\/p>\n<p>En outre, l&rsquo;inspection du module pendant les phases de nettoyage sera effectu\u00e9e afin de d\u00e9tecter des fissures, des fuites ou d&rsquo;autres d\u00e9fauts de d\u00e9sint\u00e9gration.[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=\u00a0\u00bboneThird\u00a0\u00bb width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb9813&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb qode_css_animation=\u00a0\u00bbelement_from_right\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbyes\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb background_color=\u00a0\u00bb#f4f4f4&Prime; el_class=\u00a0\u00bbmod_block imgText-resp-bottom\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h3>CONTR\u00d4LE ET MESURE DES TENSIONS DES INSTALLATIONS<\/h3>\n<p>[\/vc_column_text][vc_separator type=\u00a0\u00bbsmall\u00a0\u00bb position=\u00a0\u00bbleft\u00a0\u00bb][vc_row_inner row_type=\u00a0\u00bbrow\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb css_animation=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbsectionTable oneThirdLayout\u00a0\u00bb][vc_column_inner el_class=\u00a0\u00bboneThird\u00a0\u00bb width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb11790&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb qode_css_animation=\u00a0\u00bbelement_from_left\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb2\/3&Prime;][vc_column_text]On v\u00e9rifie le bon \u00e9tat des c\u00e2bles, des onduleurs, des tableaux \u00e9lectriques et des protections, c\u2019est-\u00e0-dire de tous les \u00e9quipements \u00e9lectriques install\u00e9s, en r\u00e9alisant un nettoyage complet et une inspection pour d\u00e9tecter des possible dommages par usure ou faute par un mauvais scellement. On proc\u00e9dera de plus au serrage de tous les contacts.<\/p>\n<p>Toutes les \u00e9quipes \u00e9lectriques seront test\u00e9 pour v\u00e9rifier son fonctionnement et son rendement. On r\u00e9alisera des ajustements du syst\u00e8me de connexion et de d\u00e9connexion, des mesures de tension et de courant des tableaux et des valeurs des onduleurs et des \u00e9quipes \u00e9lectriques.<\/p>\n<p>En cas des fautes, des surchauffes, des bourdonnements, seront prises des mesures rapides conform\u00e9ment aux instructions du manuel du fournisseur ou du service technique. En outre, on fournira au client un rapport des valeurs mesur\u00e9es et des interventions r\u00e9alis\u00e9es[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbyes\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb el_class=\u00a0\u00bbmod_block imgText-top\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h3>NETTOYAGE ET MAINTENANCE DES CABINES<\/h3>\n<p>[\/vc_column_text][vc_separator type=\u00a0\u00bbsmall\u00a0\u00bb position=\u00a0\u00bbleft\u00a0\u00bb][vc_row_inner row_type=\u00a0\u00bbrow\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb css_animation=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbimgText-top sectionTable oneThirdLayout\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb2\/3&Prime;][vc_column_text]On v\u00e9rifiera le bon \u00e9tat de conservation des cabines, en d\u00e9tectant des fissures, des dommages ou des filtrations dans les murs ext\u00e9rieurs, dans le toit et les fermetures ext\u00e9rieures. On proc\u00e9dera \u00e0 la substitution des filtres de ventilation, au contr\u00f4le des extracteurs et le nettoyage g\u00e9n\u00e9ral interne assurant l&rsquo;ordre et la fonctionnalit\u00e9.[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=\u00a0\u00bboneThird\u00a0\u00bb width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb11812&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb qode_css_animation=\u00a0\u00bbelement_from_right\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbyes\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb background_color=\u00a0\u00bb#f4f4f4&Prime; el_class=\u00a0\u00bbmod_block imgText-resp-bottom\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h3>CONTR\u00d4LE DU SYST\u00c8ME DE S\u00c9CURIT\u00c9 ET DE LA CL\u00d4TURE<\/h3>\n<p>[\/vc_column_text][vc_separator type=\u00a0\u00bbsmall\u00a0\u00bb position=\u00a0\u00bbleft\u00a0\u00bb][vc_row_inner row_type=\u00a0\u00bbrow\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb css_animation=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbsectionTable oneThirdLayout\u00a0\u00bb][vc_column_inner el_class=\u00a0\u00bboneThird\u00a0\u00bb width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb11795&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb qode_css_animation=\u00a0\u00bbelement_from_left\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb2\/3&Prime;][vc_column_text]La v\u00e9rification du bon fonctionnement du syst\u00e8me de s\u00e9curit\u00e9 et l&rsquo;\u00e9tat de cl\u00f4tures emp\u00eache toute tentative d&rsquo;intrusion. On contr\u00f4lera la qualit\u00e9 d\u2019images des cam\u00e9ras fournies pendant le jour et la nuit. En outre, on v\u00e9rifie la r\u00e9action du syst\u00e8me d\u2019alarme en cas d\u2019intrusion.<\/p>\n<p>Enfin on parcourra tout le p\u00e9rim\u00e8tre du parc pour v\u00e9rifier qu&rsquo;il n&rsquo;y a pas d&rsquo;ouvertures possibles dans les zones cl\u00f4tur\u00e9es ou en mauvais \u00e9tat.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbyes\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb el_class=\u00a0\u00bbmod_block\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h3>GRAISSAGE, SERRAGE ET GALVANISATION<\/h3>\n<p>[\/vc_column_text][vc_separator type=\u00a0\u00bbsmall\u00a0\u00bb position=\u00a0\u00bbleft\u00a0\u00bb][vc_row_inner row_type=\u00a0\u00bbrow\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb css_animation=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbimgText-top sectionTable oneThirdLayout\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb2\/3&Prime;][vc_column_text]La lubrification de toutes les pi\u00e8ces mobiles de l&rsquo;installation et le serrage des vis dans les pi\u00e8ces fixes seront effectu\u00e9s. Ces op\u00e9rations sont extr\u00eamement importantes pour le bon travail des syst\u00e8mes avec trackers et, en ce qui concerne les structures fixes, elles peuvent emp\u00eacher des situations d&rsquo;usure m\u00e9canique.<\/p>\n<p>La galvanisation pour pr\u00e9venir la corrosion sera r\u00e9vis\u00e9 si n\u00e9cessaire.[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=\u00a0\u00bboneThird\u00a0\u00bb width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb11800&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb qode_css_animation=\u00a0\u00bbelement_from_right\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbyes\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb background_color=\u00a0\u00bb#f4f4f4&Prime; el_class=\u00a0\u00bbmod_block imgText-resp-bottom\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h3>CONTR\u00d4LE DE V\u00c9G\u00c9TATION<\/h3>\n<p>[\/vc_column_text][vc_separator type=\u00a0\u00bbsmall\u00a0\u00bb position=\u00a0\u00bbleft\u00a0\u00bb][vc_row_inner row_type=\u00a0\u00bbrow\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb css_animation=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbsectionTable oneThirdLayout\u00a0\u00bb][vc_column_inner el_class=\u00a0\u00bboneThird\u00a0\u00bb width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb11804&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb qode_css_animation=\u00a0\u00bbelement_from_left\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb2\/3&Prime;][vc_column_text]Le contr\u00f4le de la croissance de la v\u00e9g\u00e9tation \u00e9vite les situations d&rsquo;ombrage et pr\u00e9vient les risques d&rsquo;incendie. Les op\u00e9rations sont effectu\u00e9es manuellement et avec des instruments m\u00e9caniques.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbyes\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb el_class=\u00a0\u00bbmod_block\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h3>CONTR\u00d4LE DES CONDUITES ET PUITS<\/h3>\n<p>[\/vc_column_text][vc_separator type=\u00a0\u00bbsmall\u00a0\u00bb position=\u00a0\u00bbleft\u00a0\u00bb][vc_row_inner row_type=\u00a0\u00bbrow\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb css_animation=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbimgText-top sectionTable oneThirdLayout\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb2\/3&Prime;][vc_column_text]L&rsquo;inspection des tuyaux et des puits est n\u00e9cessaire pour v\u00e9rifier leur int\u00e9grit\u00e9 et leur parfaite \u00e9tanch\u00e9it\u00e9, afin d&rsquo;\u00e9viter possibles infiltrations d&rsquo;eau.[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=\u00a0\u00bboneThird\u00a0\u00bb width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb5003&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb qode_css_animation=\u00a0\u00bbelement_from_right\u00a0\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbyes\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb background_color=\u00a0\u00bb#f4f4f4&Prime; el_class=\u00a0\u00bbmod_block imgText-resp-bottom\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h3>REVUE DES EXTINCTEURS<\/h3>\n<p>[\/vc_column_text][vc_separator type=\u00a0\u00bbsmall\u00a0\u00bb position=\u00a0\u00bbleft\u00a0\u00bb][vc_row_inner row_type=\u00a0\u00bbrow\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb css_animation=\u00a0\u00bb\u00a0\u00bb el_class=\u00a0\u00bbsectionTable oneThirdLayout\u00a0\u00bb][vc_column_inner el_class=\u00a0\u00bboneThird\u00a0\u00bb width=\u00a0\u00bb1\/3&Prime;][vc_single_image image=\u00a0\u00bb11808&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb qode_css_animation=\u00a0\u00bbelement_from_left\u00a0\u00bb][\/vc_column_inner][vc_column_inner width=\u00a0\u00bb2\/3&Prime;][vc_column_text]L\u2019examen p\u00e9riodique des extincteurs doivent \u00eatre effectu\u00e9s par des entreprises sp\u00e9cialis\u00e9es et certifi\u00e9es. GRUPO ZARAGOZ\u00c1 est responsable de la planification de la r\u00e9vision, de la livraison des extincteurs et du retrait aux entreprises certifi\u00e9es et du remplacement temporaire des extincteurs en cours d&rsquo;examen.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb el_class=\u00a0\u00bbmod_block pt_40&Prime;][vc_column][vc_column_text]Le but de notre service de maintenance est de maintenir le fonctionnement des installations dans des conditions optimales 365 jours par an.\u00a0Pour ce faire, nous surveillons la production quotidiennement, nous effectuons la maintenance pr\u00e9ventive, les r\u00e9parations&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":2421,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2430","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O&amp;M - GRUPO ZARAGOZ\u00c1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grupozaragoza.com\/fr\/energie-renouvelable\/om\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O&amp;M - GRUPO ZARAGOZ\u00c1\" \/>\n<meta property=\"og:description\" content=\"[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb el_class=\u00a0\u00bbmod_block pt_40&Prime;][vc_column][vc_column_text]Le but de notre service de maintenance est de maintenir le fonctionnement des installations dans des conditions optimales 365 jours par an.\u00a0Pour ce faire, nous surveillons la production quotidiennement, nous effectuons la maintenance pr\u00e9ventive, les r\u00e9parations...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grupozaragoza.com\/fr\/energie-renouvelable\/om\/\" \/>\n<meta property=\"og:site_name\" content=\"GRUPO ZARAGOZ\u00c1\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-09T06:44:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.grupozaragoza.com\\\/fr\\\/energie-renouvelable\\\/om\\\/\",\"url\":\"https:\\\/\\\/www.grupozaragoza.com\\\/fr\\\/energie-renouvelable\\\/om\\\/\",\"name\":\"O&M - GRUPO ZARAGOZ\u00c1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupozaragoza.com\\\/#website\"},\"datePublished\":\"2017-07-11T07:55:07+00:00\",\"dateModified\":\"2024-08-09T06:44:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.grupozaragoza.com\\\/fr\\\/energie-renouvelable\\\/om\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.grupozaragoza.com\\\/fr\\\/energie-renouvelable\\\/om\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.grupozaragoza.com\\\/fr\\\/energie-renouvelable\\\/om\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.grupozaragoza.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energie Renouvelable\",\"item\":\"https:\\\/\\\/www.grupozaragoza.com\\\/fr\\\/energie-renouvelable\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O&#038;M\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.grupozaragoza.com\\\/#website\",\"url\":\"https:\\\/\\\/www.grupozaragoza.com\\\/\",\"name\":\"GRUPO ZARAGOZ\u00c1\",\"description\":\"Ingenieria &amp; Arquitectura Creativa\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.grupozaragoza.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.grupozaragoza.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.grupozaragoza.com\\\/#organization\",\"name\":\"GRUPO ZARAGOZ\u00c1\",\"url\":\"https:\\\/\\\/www.grupozaragoza.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.grupozaragoza.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.grupozaragoza.com\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/logo_zaragoza.png\",\"contentUrl\":\"https:\\\/\\\/www.grupozaragoza.com\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/logo_zaragoza.png\",\"width\":676,\"height\":180,\"caption\":\"GRUPO ZARAGOZ\u00c1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupozaragoza.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/grupozaragoza\\\/\",\"https:\\\/\\\/www.instagram.com\\\/grupozaragoza_com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O&M - GRUPO ZARAGOZ\u00c1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grupozaragoza.com\/fr\/energie-renouvelable\/om\/","og_locale":"fr_FR","og_type":"article","og_title":"O&M - GRUPO ZARAGOZ\u00c1","og_description":"[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbgrid\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb el_class=\u00a0\u00bbmod_block pt_40&Prime;][vc_column][vc_column_text]Le but de notre service de maintenance est de maintenir le fonctionnement des installations dans des conditions optimales 365 jours par an.\u00a0Pour ce faire, nous surveillons la production quotidiennement, nous effectuons la maintenance pr\u00e9ventive, les r\u00e9parations...","og_url":"https:\/\/www.grupozaragoza.com\/fr\/energie-renouvelable\/om\/","og_site_name":"GRUPO ZARAGOZ\u00c1","article_modified_time":"2024-08-09T06:44:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.grupozaragoza.com\/fr\/energie-renouvelable\/om\/","url":"https:\/\/www.grupozaragoza.com\/fr\/energie-renouvelable\/om\/","name":"O&M - GRUPO ZARAGOZ\u00c1","isPartOf":{"@id":"https:\/\/www.grupozaragoza.com\/#website"},"datePublished":"2017-07-11T07:55:07+00:00","dateModified":"2024-08-09T06:44:15+00:00","breadcrumb":{"@id":"https:\/\/www.grupozaragoza.com\/fr\/energie-renouvelable\/om\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grupozaragoza.com\/fr\/energie-renouvelable\/om\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grupozaragoza.com\/fr\/energie-renouvelable\/om\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.grupozaragoza.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Energie Renouvelable","item":"https:\/\/www.grupozaragoza.com\/fr\/energie-renouvelable\/"},{"@type":"ListItem","position":3,"name":"O&#038;M"}]},{"@type":"WebSite","@id":"https:\/\/www.grupozaragoza.com\/#website","url":"https:\/\/www.grupozaragoza.com\/","name":"GRUPO ZARAGOZ\u00c1","description":"Ingenieria &amp; Arquitectura Creativa","publisher":{"@id":"https:\/\/www.grupozaragoza.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grupozaragoza.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.grupozaragoza.com\/#organization","name":"GRUPO ZARAGOZ\u00c1","url":"https:\/\/www.grupozaragoza.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.grupozaragoza.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.grupozaragoza.com\/wp-content\/uploads\/2017\/08\/logo_zaragoza.png","contentUrl":"https:\/\/www.grupozaragoza.com\/wp-content\/uploads\/2017\/08\/logo_zaragoza.png","width":676,"height":180,"caption":"GRUPO ZARAGOZ\u00c1"},"image":{"@id":"https:\/\/www.grupozaragoza.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/grupozaragoza\/","https:\/\/www.instagram.com\/grupozaragoza_com\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.grupozaragoza.com\/fr\/wp-json\/wp\/v2\/pages\/2430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grupozaragoza.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.grupozaragoza.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupozaragoza.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupozaragoza.com\/fr\/wp-json\/wp\/v2\/comments?post=2430"}],"version-history":[{"count":6,"href":"https:\/\/www.grupozaragoza.com\/fr\/wp-json\/wp\/v2\/pages\/2430\/revisions"}],"predecessor-version":[{"id":11825,"href":"https:\/\/www.grupozaragoza.com\/fr\/wp-json\/wp\/v2\/pages\/2430\/revisions\/11825"}],"up":[{"embeddable":true,"href":"https:\/\/www.grupozaragoza.com\/fr\/wp-json\/wp\/v2\/pages\/2421"}],"wp:attachment":[{"href":"https:\/\/www.grupozaragoza.com\/fr\/wp-json\/wp\/v2\/media?parent=2430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}